{"id":46,"date":"2018-01-15T18:54:51","date_gmt":"2018-01-15T17:54:51","guid":{"rendered":"http:\/\/pragma-security.com\/?page_id=46"},"modified":"2022-03-01T18:16:27","modified_gmt":"2022-03-01T17:16:27","slug":"pragma-security-cybersecurite","status":"publish","type":"page","link":"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/","title":{"rendered":"A propos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"46\" class=\"elementor elementor-46\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57a7629 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"57a7629\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-783ad6e1\" data-id=\"783ad6e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1ec013 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e1ec013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-779ab389 elementor-widget elementor-widget-heading\" data-id=\"779ab389\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">QUI SOMMES-NOUS?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cefd9a8 elementor-widget elementor-widget-text-editor\" data-id=\"2cefd9a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Pragma Security est votre partenaire en cybers\u00e9curit\u00e9 manag\u00e9e.\u00a0<\/h5><div>Pragma Security propose aux sites internet et r\u00e9seaux fran\u00e7ais un ensemble de solutions pour se pr\u00e9munir contre les attaques DDoS et autres failles de s\u00e9curit\u00e9 nuisibles \u00e0 leurs organisations.<\/div><div>Au travers de notre propre r\u00e9seau bas\u00e9 en France et en partenariat avec Qrator Labs au niveau international, nous r\u00e9pondons avec efficacit\u00e9 aux diff\u00e9rents types d&#8217;attaques que vous pouvez conna\u00eetre.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-601b7a4c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"601b7a4c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-69914a8\" data-id=\"69914a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40917cd0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"40917cd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Matthieu-Texier.png\" class=\"attachment-full size-full wp-image-1228\" alt=\"\" srcset=\"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Matthieu-Texier.png 1000w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Matthieu-Texier-300x300.png 300w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Matthieu-Texier-150x150.png 150w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Matthieu-Texier-768x768.png 768w\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Matthieu Texier<\/h3><p class=\"elementor-image-box-description\">Co-fondateur et dirigeant<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6675e067\" data-id=\"6675e067\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4adbdb96 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"4adbdb96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Paolo-Lucente.png\" class=\"attachment-full size-full wp-image-1229\" alt=\"\" srcset=\"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Paolo-Lucente.png 1000w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Paolo-Lucente-300x300.png 300w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Paolo-Lucente-150x150.png 150w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Paolo-Lucente-768x768.png 768w\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Paolo Lucente<\/h3><p class=\"elementor-image-box-description\">Co-fondateur - T\u00e9l\u00e9m\u00e9trie Big Data<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7cd1a580\" data-id=\"7cd1a580\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-629922b7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"629922b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/09\/Pragma-Security-Equipe-Luc-de-la-Guerrande.png\" class=\"attachment-full size-full wp-image-1319\" alt=\"\" srcset=\"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/09\/Pragma-Security-Equipe-Luc-de-la-Guerrande.png 3000w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/09\/Pragma-Security-Equipe-Luc-de-la-Guerrande-300x300.png 300w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/09\/Pragma-Security-Equipe-Luc-de-la-Guerrande-1024x1024.png 1024w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/09\/Pragma-Security-Equipe-Luc-de-la-Guerrande-150x150.png 150w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/09\/Pragma-Security-Equipe-Luc-de-la-Guerrande-768x768.png 768w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/09\/Pragma-Security-Equipe-Luc-de-la-Guerrande-1536x1536.png 1536w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/09\/Pragma-Security-Equipe-Luc-de-la-Guerrande-2048x2048.png 2048w\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Luc de la Guerrande<\/h3><p class=\"elementor-image-box-description\">Directeur d\u00e9veloppement commercial<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58cbbd7 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58cbbd7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-de512ef\" data-id=\"de512ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-721119d elementor-widget elementor-widget-text-editor\" data-id=\"721119d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fort de 18 ann\u00e9es d&#8217;exp\u00e9rience pass\u00e9es au sein d&#8217;Alcatel-Lucent, Ericsson, Juniper Networks et Arbor Network entre autres, Matthieu dispose d&#8217;une vision forte du march\u00e9 allant des r\u00e9seaux fixes et mobiles jusqu&#8217;aux fournisseurs de cloud. Matthieu sait conseiller et accompagner les entreprises pendant leurs phases cl\u00e9s de transition et d\u00e9velopper des opportunit\u00e9s complexes dans des environnements innovants.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a23a57 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"8a23a57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-grow elementor-repeater-item-8b93740\" href=\"https:\/\/fr.linkedin.com\/in\/mtexier\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-animation-grow elementor-repeater-item-d2b7695\" href=\"https:\/\/twitter.com\/matt_texier\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-54864d5\" data-id=\"54864d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-875adc9 elementor-widget elementor-widget-text-editor\" data-id=\"875adc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En plus d\u2019\u00eatre l\u2019auteur du logiciel open-source PMACCT qu\u2019il ne cesse de d\u2019\u00e9toffer, Paolo est le co-fondateur de Pragma Innovation, la branche R&amp;D de Pragma Security. Auparavant, Paolo a occup\u00e9 diff\u00e9rents postes en ing\u00e9nierie au sein de grands fournisseurs de services nationaux et internationaux en Europe et du r\u00e9seau de la recherche en Italie du Sud, dans la r\u00e9gion des Pouilles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-996f8d0 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"996f8d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-grow elementor-repeater-item-8b93740\" href=\"http:\/\/www.linkedin.com\/in\/plucente\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-animation-grow elementor-repeater-item-d2b7695\" href=\"https:\/\/twitter.com\/paolo_lucente\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a39a2f7\" data-id=\"a39a2f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b859d8 elementor-widget elementor-widget-text-editor\" data-id=\"3b859d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u2019un temp\u00e9rament dynamique et entrepreneurial, Luc a rapidement rejoint l\u2019\u00e9quipe Pragma Security fin 2018, apr\u00e8s plus de 20 ans pass\u00e9s dans l\u2019industrie des t\u00e9l\u00e9coms.\u00a0En tant que Directeur des ventes chez Neo Telecoms (devenu Zayo France), Luc a tr\u00e8s fortement d\u00e9velopp\u00e9 l\u2019activit\u00e9 en France, mont\u00e9 une \u00e9quipe commerciale et ouvert les march\u00e9s du Benelux et de la Suisse. Plusieurs ann\u00e9es au sein d\u2019InterCloud ont compl\u00e9t\u00e9 son expertise dans l\u2019accompagnement des grands comptes dans leurs projets de migration et de s\u00e9curisation de leurs infrastructures et applications vers le Cloud.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddb5237 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"ddb5237\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-grow elementor-repeater-item-8b93740\" href=\"https:\/\/www.linkedin.com\/in\/delaguerrande\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-animation-grow elementor-repeater-item-d2b7695\" href=\"https:\/\/twitter.com\/ldelaguerrande\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad96de6 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad96de6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9844680\" data-id=\"9844680\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-265a49a\" data-id=\"265a49a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b846ecf elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b846ecf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Solene-Souquet.png\" class=\"attachment-full size-full wp-image-1252\" alt=\"\" srcset=\"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Solene-Souquet.png 1000w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Solene-Souquet-300x300.png 300w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Solene-Souquet-150x150.png 150w, https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Solene-Souquet-768x768.png 768w\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sol\u00e8ne Souquet<\/h3><p class=\"elementor-image-box-description\">Marcom<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb59e4e elementor-widget elementor-widget-text-editor\" data-id=\"eb59e4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sol\u00e8ne \u00e9volue depuis plus de 10 ans dans l&#8217;univers de l&#8217;infrastructure Internet. Elle a notamment particip\u00e9 au lancement et \u00e0 la croissance de plusieurs points d&#8217;\u00e9change en France et en Afrique.\u00a0Au sein de Pragma Security, Sol\u00e8ne met \u00e0 contribution ses comp\u00e9tences en communication et marketing afin de d\u00e9velopper la visibilit\u00e9 des offres de cybers\u00e9curit\u00e9 sur le march\u00e9 fran\u00e7ais.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d622230 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"d622230\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-grow elementor-repeater-item-8b93740\" href=\"https:\/\/www.linkedin.com\/in\/solenesouquet\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-animation-grow elementor-repeater-item-d2b7695\" href=\"https:\/\/twitter.com\/solenetweets\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b6c24b1\" data-id=\"b6c24b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40c69dfd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40c69dfd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6267ceab\" data-id=\"6267ceab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ccb8303 elementor-widget elementor-widget-spacer\" data-id=\"1ccb8303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e7c02c4 elementor-widget elementor-widget-heading\" data-id=\"7e7c02c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-medium\">Suivez-nous sur les r\u00e9seaux sociaux<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43e5d531 elementor-widget elementor-widget-spacer\" data-id=\"43e5d531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48b0e0f1 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"48b0e0f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-6733628\" href=\"https:\/\/www.facebook.com\/pragmasec\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-4c75ed4\" href=\"https:\/\/www.twitter.com\/pragmasecurity\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin-in elementor-repeater-item-fe95a66\" href=\"https:\/\/www.linkedin.com\/company\/pragma-security\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin-in<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>QUI SOMMES-NOUS? Pragma Security est votre partenaire en cybers\u00e9curit\u00e9 manag\u00e9e.\u00a0 Pragma Security propose aux sites internet et r\u00e9seaux fran\u00e7ais un ensemble de solutions pour se pr\u00e9munir contre les attaques DDoS et autres failles de s\u00e9curit\u00e9 nuisibles \u00e0 leurs organisations.Au travers de notre propre r\u00e9seau bas\u00e9 en France et en partenariat avec Qrator Labs au niveau [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-46","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pragma Security - leader en protection anti-DDoS et cybers\u00e9curit\u00e9<\/title>\n<meta name=\"description\" content=\"Pragma Security est un fournisseur de solutions de cybers\u00e9curit\u00e9 et le leader en protection anti-DDoS sur le march\u00e9 fran\u00e7ais. Nous s\u00e9curisons et maintenons disponibles vos sites et ressources web.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pragma Security - leader en protection anti-DDoS et cybers\u00e9curit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Pragma Security est un fournisseur de solutions de cybers\u00e9curit\u00e9 et le leader en protection anti-DDoS sur le march\u00e9 fran\u00e7ais. Nous s\u00e9curisons et maintenons disponibles vos sites et ressources web.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/\" \/>\n<meta property=\"og:site_name\" content=\"Pragma Security\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-01T17:16:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Matthieu-Texier.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pragma-security.com\\\/index.php\\\/pragma-security-cybersecurite\\\/\",\"url\":\"https:\\\/\\\/pragma-security.com\\\/index.php\\\/pragma-security-cybersecurite\\\/\",\"name\":\"Pragma Security - leader en protection anti-DDoS et cybers\u00e9curit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pragma-security.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pragma-security.com\\\/index.php\\\/pragma-security-cybersecurite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pragma-security.com\\\/index.php\\\/pragma-security-cybersecurite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pragma-security.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Pragma-Security-Equipe-Matthieu-Texier.png\",\"datePublished\":\"2018-01-15T17:54:51+00:00\",\"dateModified\":\"2022-03-01T17:16:27+00:00\",\"description\":\"Pragma Security est un fournisseur de solutions de cybers\u00e9curit\u00e9 et le leader en protection anti-DDoS sur le march\u00e9 fran\u00e7ais. Nous s\u00e9curisons et maintenons disponibles vos sites et ressources web.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pragma-security.com\\\/index.php\\\/pragma-security-cybersecurite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pragma-security.com\\\/index.php\\\/pragma-security-cybersecurite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pragma-security.com\\\/index.php\\\/pragma-security-cybersecurite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pragma-security.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Pragma-Security-Equipe-Matthieu-Texier.png\",\"contentUrl\":\"https:\\\/\\\/pragma-security.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Pragma-Security-Equipe-Matthieu-Texier.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pragma-security.com\\\/index.php\\\/pragma-security-cybersecurite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/pragma-security.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A propos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pragma-security.com\\\/#website\",\"url\":\"https:\\\/\\\/pragma-security.com\\\/\",\"name\":\"Pragma Security\",\"description\":\"Protection anti-DDoS | DNS | WAF\",\"publisher\":{\"@id\":\"https:\\\/\\\/pragma-security.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pragma-security.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pragma-security.com\\\/#organization\",\"name\":\"Pragma Security\",\"url\":\"https:\\\/\\\/pragma-security.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pragma-security.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pragma-security.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Pragma-JPG.jpg\",\"contentUrl\":\"https:\\\/\\\/pragma-security.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Pragma-JPG.jpg\",\"width\":436,\"height\":394,\"caption\":\"Pragma Security\"},\"image\":{\"@id\":\"https:\\\/\\\/pragma-security.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pragma Security - leader en protection anti-DDoS et cybers\u00e9curit\u00e9","description":"Pragma Security est un fournisseur de solutions de cybers\u00e9curit\u00e9 et le leader en protection anti-DDoS sur le march\u00e9 fran\u00e7ais. Nous s\u00e9curisons et maintenons disponibles vos sites et ressources web.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/","og_locale":"fr_FR","og_type":"article","og_title":"Pragma Security - leader en protection anti-DDoS et cybers\u00e9curit\u00e9","og_description":"Pragma Security est un fournisseur de solutions de cybers\u00e9curit\u00e9 et le leader en protection anti-DDoS sur le march\u00e9 fran\u00e7ais. Nous s\u00e9curisons et maintenons disponibles vos sites et ressources web.","og_url":"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/","og_site_name":"Pragma Security","article_modified_time":"2022-03-01T17:16:27+00:00","og_image":[{"url":"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Matthieu-Texier.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/","url":"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/","name":"Pragma Security - leader en protection anti-DDoS et cybers\u00e9curit\u00e9","isPartOf":{"@id":"https:\/\/pragma-security.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/#primaryimage"},"image":{"@id":"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/#primaryimage"},"thumbnailUrl":"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Matthieu-Texier.png","datePublished":"2018-01-15T17:54:51+00:00","dateModified":"2022-03-01T17:16:27+00:00","description":"Pragma Security est un fournisseur de solutions de cybers\u00e9curit\u00e9 et le leader en protection anti-DDoS sur le march\u00e9 fran\u00e7ais. Nous s\u00e9curisons et maintenons disponibles vos sites et ressources web.","breadcrumb":{"@id":"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/#primaryimage","url":"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Matthieu-Texier.png","contentUrl":"https:\/\/pragma-security.com\/wp-content\/uploads\/2020\/07\/Pragma-Security-Equipe-Matthieu-Texier.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/pragma-security.com\/index.php\/pragma-security-cybersecurite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pragma-security.com\/"},{"@type":"ListItem","position":2,"name":"A propos"}]},{"@type":"WebSite","@id":"https:\/\/pragma-security.com\/#website","url":"https:\/\/pragma-security.com\/","name":"Pragma Security","description":"Protection anti-DDoS | DNS | WAF","publisher":{"@id":"https:\/\/pragma-security.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pragma-security.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/pragma-security.com\/#organization","name":"Pragma Security","url":"https:\/\/pragma-security.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pragma-security.com\/#\/schema\/logo\/image\/","url":"https:\/\/pragma-security.com\/wp-content\/uploads\/2018\/01\/Pragma-JPG.jpg","contentUrl":"https:\/\/pragma-security.com\/wp-content\/uploads\/2018\/01\/Pragma-JPG.jpg","width":436,"height":394,"caption":"Pragma Security"},"image":{"@id":"https:\/\/pragma-security.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/pragma-security.com\/index.php\/wp-json\/wp\/v2\/pages\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pragma-security.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pragma-security.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pragma-security.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pragma-security.com\/index.php\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":28,"href":"https:\/\/pragma-security.com\/index.php\/wp-json\/wp\/v2\/pages\/46\/revisions"}],"predecessor-version":[{"id":1320,"href":"https:\/\/pragma-security.com\/index.php\/wp-json\/wp\/v2\/pages\/46\/revisions\/1320"}],"wp:attachment":[{"href":"https:\/\/pragma-security.com\/index.php\/wp-json\/wp\/v2\/media?parent=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}